{"id":3534,"date":"2009-02-20T16:01:00","date_gmt":"2009-02-20T09:01:00","guid":{"rendered":"https:\/\/bma-csc.bangkok.go.th\/csc\/?post_type=docs&amp;p=3534"},"modified":"2009-02-20T16:01:00","modified_gmt":"2009-02-20T09:01:00","password":"","slug":"2552-v334","status":"publish","type":"docs","link":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/","title":{"rendered":"2552-\u0e274 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d ****\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49****"},"content":{"rendered":"\n<p style=\"font-size:25px\"><strong>[\u0e1b\u0e352552-\u0e274] \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u0e19\u0e23 1006\/\u0e27 4 \u0e25\u0e27. 20 \u0e01.\u0e1e. 2552<\/p>\n\n\n\n<p class=\"has-medium-font-size\"><strong>\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07<\/strong><\/p>\n\n\n\n<p class=\"has-medium-font-size\">\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25 : <strong>\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e2f <\/strong>\u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e01\u0e17\u0e21.\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e44\u0e1b\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e42\u0e14\u0e22\u0e02\u0e13\u0e30\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d \u0e01.\u0e01. \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e01\u0e17\u0e21.&nbsp;\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30 \u0e02\u0e23\u0e01.\u0e21\u0e32\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e40\u0e1b\u0e47\u0e19 \u0e02\u0e23\u0e01.\u0e01\u0e17\u0e21.\u0e2a\u0e32\u0e21\u0e31\u0e0d<\/p>\n\n\n\n<p><img decoding=\"async\" src=\"http:\/\/203.155.220.238\/csc\/images\/Picture\/Deco\/icon_readmore2.gif\" alt=\"\"><strong><a href=\"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-content\/uploads\/2022\/10\/52v4.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u0e2d\u0e48\u0e32\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>[\u0e1b\u0e352552-\u0e274] \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e19\u0e23 1006\/\u0e27 4 \u0e25\u0e27. 20 \u0e01.\u0e1e. 2552 \u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25 : \u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e2f \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e01\u0e17\u0e21.\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e44\u0e1b\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e42\u0e14\u0e22\u0e02\u0e13\u0e30\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d \u0e01.\u0e01. \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e01\u0e17\u0e21.&nbsp;\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30 \u0e02\u0e23\u0e01.\u0e21\u0e32\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e40\u0e1b\u0e47\u0e19 \u0e02\u0e23\u0e01.\u0e01\u0e17\u0e21.\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e2d\u0e48\u0e32\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_gspb_post_css":"","footnotes":""},"doc_category":[20],"doc_tag":[],"class_list":["post-3534","docs","type-docs","status-publish","hentry","doc_category-3-book_korpor3"],"year_month":"2026-05","word_count":2,"total_views":"23","reactions":{"happy":"0","normal":"0","sad":"0"},"author_info":{"name":"admincsc01","author_nicename":"admincsc01","author_url":"https:\/\/bma-csc.bangkok.go.th\/csc\/author\/admincsc01\/"},"doc_category_info":[{"term_name":"3.3 \u0e2b\u0e21\u0e27\u0e14\u0e2b\u0e21\u0e39\u0e48 \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e23\u0e2b\u0e32 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e49\u0e07 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e27\u0e38\u0e12\u0e34 \u0e01\u0e32\u0e23\u0e17\u0e14\u0e25\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e25\u0e31\u0e1a\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e48\u0e2d\u0e2d\u0e32\u0e22\u0e38\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23","term_url":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs-category\/3-book_korpor3\/"}],"doc_tag_info":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>2552-\u0e274 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d ****\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49**** | \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"2552-\u0e274 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d ****\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49**** | \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\" \/>\r\n<meta property=\"og:description\" content=\"[\u0e1b\u0e352552-\u0e274] \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e19\u0e23 1006\/\u0e27 4 \u0e25\u0e27. 20 \u0e01.\u0e1e. 2552 \u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25 : \u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e2f \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e01\u0e17\u0e21.\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e44\u0e1b\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e42\u0e14\u0e22\u0e02\u0e13\u0e30\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d \u0e01.\u0e01. \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e01\u0e17\u0e21.&nbsp;\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30 \u0e02\u0e23\u0e01.\u0e21\u0e32\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e40\u0e1b\u0e47\u0e19 \u0e02\u0e23\u0e01.\u0e01\u0e17\u0e21.\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e2d\u0e48\u0e32\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/\" \/>\r\n<meta property=\"og:site_name\" content=\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\" \/>\r\n<meta property=\"og:image\" content=\"http:\/\/203.155.220.238\/csc\/images\/Picture\/Deco\/icon_readmore2.gif\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/docs\\\/2552-v334\\\/\",\"url\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/docs\\\/2552-v334\\\/\",\"name\":\"2552-\u0e274 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d ****\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49**** | \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/docs\\\/2552-v334\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/docs\\\/2552-v334\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/203.155.220.238\\\/csc\\\/images\\\/Picture\\\/Deco\\\/icon_readmore2.gif\",\"datePublished\":\"2009-02-20T09:01:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/docs\\\/2552-v334\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/docs\\\/2552-v334\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/docs\\\/2552-v334\\\/#primaryimage\",\"url\":\"http:\\\/\\\/203.155.220.238\\\/csc\\\/images\\\/Picture\\\/Deco\\\/icon_readmore2.gif\",\"contentUrl\":\"http:\\\/\\\/203.155.220.238\\\/csc\\\/images\\\/Picture\\\/Deco\\\/icon_readmore2.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/docs\\\/2552-v334\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01\",\"item\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Docs\",\"item\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/docs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2552-\u0e274 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d ****\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49****\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/#website\",\"url\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/#organization\",\"name\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\",\"url\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23-3.png\",\"contentUrl\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/cropped-\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23-3.png\",\"width\":599,\"height\":100,\"caption\":\"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\"},\"image\":{\"@id\":\"https:\\\/\\\/bma-csc.bangkok.go.th\\\/csc\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2552-\u0e274 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d ****\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49**** | \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/","og_locale":"en_US","og_type":"article","og_title":"2552-\u0e274 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d ****\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49**** | \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23","og_description":"[\u0e1b\u0e352552-\u0e274] \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e19\u0e23 1006\/\u0e27 4 \u0e25\u0e27. 20 \u0e01.\u0e1e. 2552 \u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e32\u0e23\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25 : \u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49\u0e2f \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e49\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e01\u0e17\u0e21.\u0e2a\u0e32\u0e21\u0e31\u0e0d\u0e44\u0e1b\u0e2a\u0e31\u0e07\u0e01\u0e31\u0e14\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e42\u0e14\u0e22\u0e02\u0e13\u0e30\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e32\u0e23\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d \u0e01.\u0e01. \u0e01\u0e33\u0e2b\u0e19\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e43\u0e2b\u0e49\u0e2a\u0e2d\u0e14\u0e04\u0e25\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e02\u0e2d\u0e07\u0e01\u0e17\u0e21.&nbsp;\u0e42\u0e14\u0e22\u0e1b\u0e23\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e25\u0e31\u0e01\u0e40\u0e01\u0e13\u0e11\u0e4c\u0e41\u0e25\u0e30\u0e27\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e42\u0e2d\u0e19\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19\u0e41\u0e25\u0e30 \u0e02\u0e23\u0e01.\u0e21\u0e32\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e40\u0e1b\u0e47\u0e19 \u0e02\u0e23\u0e01.\u0e01\u0e17\u0e21.\u0e2a\u0e32\u0e21\u0e31\u0e0d \u0e2d\u0e48\u0e32\u0e19\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14","og_url":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/","og_site_name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23","og_image":[{"url":"http:\/\/203.155.220.238\/csc\/images\/Picture\/Deco\/icon_readmore2.gif","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/","url":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/","name":"2552-\u0e274 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d ****\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49**** | \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23","isPartOf":{"@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/#primaryimage"},"image":{"@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/#primaryimage"},"thumbnailUrl":"http:\/\/203.155.220.238\/csc\/images\/Picture\/Deco\/icon_readmore2.gif","datePublished":"2009-02-20T09:01:00+00:00","breadcrumb":{"@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/#primaryimage","url":"http:\/\/203.155.220.238\/csc\/images\/Picture\/Deco\/icon_readmore2.gif","contentUrl":"http:\/\/203.155.220.238\/csc\/images\/Picture\/Deco\/icon_readmore2.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/2552-v334\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0e2b\u0e19\u0e49\u0e32\u0e2b\u0e25\u0e31\u0e01","item":"https:\/\/bma-csc.bangkok.go.th\/csc\/"},{"@type":"ListItem","position":2,"name":"Docs","item":"https:\/\/bma-csc.bangkok.go.th\/csc\/docs\/"},{"@type":"ListItem","position":3,"name":"2552-\u0e274 \u0e01\u0e32\u0e23\u0e42\u0e2d\u0e19 \u0e02\u0e23\u0e01.\u0e1e\u0e25\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e2a\u0e32\u0e21\u0e31\u0e0d ****\u0e19\u0e33\u0e21\u0e32\u0e1b\u0e23\u0e31\u0e1a\u0e43\u0e0a\u0e49****"}]},{"@type":"WebSite","@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/#website","url":"https:\/\/bma-csc.bangkok.go.th\/csc\/","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23","description":"","publisher":{"@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bma-csc.bangkok.go.th\/csc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/#organization","name":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23","url":"https:\/\/bma-csc.bangkok.go.th\/csc\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/#\/schema\/logo\/image\/","url":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-content\/uploads\/2024\/03\/cropped-\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23-3.png","contentUrl":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-content\/uploads\/2024\/03\/cropped-\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23-3.png","width":599,"height":100,"caption":"\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e02\u0e49\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23"},"image":{"@id":"https:\/\/bma-csc.bangkok.go.th\/csc\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-json\/wp\/v2\/docs\/3534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-json\/wp\/v2\/docs"}],"about":[{"href":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-json\/wp\/v2\/types\/docs"}],"author":[{"embeddable":true,"href":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-json\/wp\/v2\/comments?post=3534"}],"version-history":[{"count":0,"href":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-json\/wp\/v2\/docs\/3534\/revisions"}],"wp:attachment":[{"href":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-json\/wp\/v2\/media?parent=3534"}],"wp:term":[{"taxonomy":"doc_category","embeddable":true,"href":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-json\/wp\/v2\/doc_category?post=3534"},{"taxonomy":"doc_tag","embeddable":true,"href":"https:\/\/bma-csc.bangkok.go.th\/csc\/wp-json\/wp\/v2\/doc_tag?post=3534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}